{"id":19,"name":"Richarson Bigot","url":"","description":"Avocat au barreau d'Aquin, journaliste et amant de la lecture et l'\u00e9criture, Richarson Bigot se donne corps et \u00e2me au journalisme. Un m\u00e9tier auquel il s'adonne depuis plusieurs ann\u00e9es \u00e0 travers des m\u00e9dias de renom. Depuis 2019 il est membre de l'\u00e9mission Mardi Alternative diffus\u00e9e sur Cara\u00efbes FM. Originaire de l'Asile, Richarson Bigot veut que sa plume soit toujours utile \u00e0 la soci\u00e9t\u00e9 ha\u00eftienne qu'il porte dans les tr\u00e9fonds de son coeur.","link":"https:\/\/alerte24.info\/en\/author\/richarson-bigot\/","slug":"richarson-bigot","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/568ce0ef5589a4091848fbe074a67114a23ba74ecfb707cd16342438c0668d47?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/568ce0ef5589a4091848fbe074a67114a23ba74ecfb707cd16342438c0668d47?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/568ce0ef5589a4091848fbe074a67114a23ba74ecfb707cd16342438c0668d47?s=96&d=mm&r=g"},"meta":[],"elementor_introduction":"","_links":{"self":[{"href":"https:\/\/alerte24.info\/en\/wp-json\/wp\/v2\/users\/19","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alerte24.info\/en\/wp-json\/wp\/v2\/users"}]}}